{"id":276,"date":"2022-07-06T08:42:41","date_gmt":"2022-07-06T08:42:41","guid":{"rendered":"http:\/\/espaciokuatro.eu\/?p=276"},"modified":"2024-01-31T21:23:22","modified_gmt":"2024-01-31T21:23:22","slug":"taller-de-inmersion-sonora-vacaciones","status":"publish","type":"post","link":"https:\/\/espaciokuatro.eu\/index.php\/2022\/07\/06\/taller-de-inmersion-sonora-vacaciones\/","title":{"rendered":"Residencias Art\u00edsticas, Talleres, Retiros, Actuaciones y Convivencias"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Buscas un espacio di\u00e1fano para desarrollar actividades rodeado de naturaleza, sol y playa? Y que tiene la opci\u00f3n de alojamiento para hasta 18 personas?<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Estamos abiertos a charlar contigo y ayudarte realizar tus actividades aqu\u00ed.  Tambi\u00e9n esta la posibilidad de colaborar con profesionales de la zona: Cocineros, t\u00e9cnicos de luz y sonido,  docentes para impartir talleres, masajistas, m\u00fasicos, coaches art\u00edsticos y apoyo en tu proyecto.    <\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"http:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/Taller-Teatro-1024x680.jpeg\" alt=\"\" class=\"wp-image-376\" srcset=\"https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/Taller-Teatro-1024x680.jpeg 1024w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/Taller-Teatro-300x199.jpeg 300w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/Taller-Teatro-768x510.jpeg 768w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/Taller-Teatro.jpeg 1242w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Taller de cabaret, yoga y playa<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfA qui\u00e9n se dirige?<\/h2>\n\n\n\n<p>A personas, grupos y compa\u00f1\u00edas que tienen proyectos y buscan un lugar adecuado para ensayar, crear, indagar, investigar, colaborar o realizar trabajos en grupo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contenidos<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Espacio\/teatro di\u00e1fano de 100 metros cuadrados con suelo de madera<\/li><li>Alojamiento estilo dormitorio para max. 11 personas<\/li><li>Cocina amplia y dos ba\u00f1os, cada una con dos duchas y dos inodoras<\/li><li>Alojamiento suplementario en un apartamento para max. 7 personas<\/li><li>Espacio amplio de campo privado que cuenta con huerta, temascal y zonas de relajaci\u00f3n. <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Qui\u00e9n lo maneja<\/h2>\n\n\n\n<p>Helena Chalverus<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/CIMG9348-1024x768.jpg\" alt=\"\" class=\"wp-image-369\" srcset=\"https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/CIMG9348-1024x768.jpg 1024w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/CIMG9348-300x225.jpg 300w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/CIMG9348-768x576.jpg 768w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/CIMG9348-1536x1152.jpg 1536w, https:\/\/espaciokuatro.eu\/wp-content\/uploads\/2023\/06\/CIMG9348.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Helena Chalverus<\/figcaption><\/figure>\n\n\n\n<p>Helena viene del mundo de la danza siendo diplomada en danza contempor\u00e1nea y coreograf\u00eda de Colorado College, Colorado, EEUU en 1999.  He venido a vivir en Espa\u00f1a en el 2000 para bailar y dirigir obras en el mundo de la danza contempor\u00e1nea y estudiar flamenco.   Lleva 20 a\u00f1os viviendo en Cadiz donde imparte clases de yoga y danza e imparte retiros.  Actualmente vive y maneja Espacio Kuatro donde promueve residencias art\u00edsticas, retiros, eventos y espect\u00e1culos.  <\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">M\u00e1s informaci\u00f3n: 681-26-22-33<br> <a href=\"mailto:info@espaciokuatro.eu\" target=\"_blank\" rel=\"noreferrer noopener\">espaciokuatro<\/a>@gmail.com <br><a href=\"https:\/\/t.me\/espaciokuatro\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/instagram\/espacio_kuatro<\/a><\/h2>\n\n\n\n<div class=\"wp-block-joinchat-button joinchat-button--qr-both has-border-color\" style=\"border-color:#25d366;border-radius:30px;border-style:solid;border-width:6px\"><figure><figcaption>Escanea el c\u00f3digo<\/figcaption><a class=\"joinchat-button__qr has-border-color\" style=\"border-color:#25d366;border-radius:30px;border-style:solid;border-width:6px\" href=\"#whatsapp\"><\/a><\/figure><a class=\"wp-block-button__link joinchat-button__link has-ffffff-color has-text-color has-background has-border-color\" style=\"border-color:#25d366;border-radius:30px;border-style:solid;border-width:6px;background-color:#25d366\" href=\"#whatsapp\"><span><strong>Open Chat<\/strong><\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Buscas un espacio di\u00e1fano para desarrollar actividades rodeado de naturaleza, sol y playa? Y que tiene la opci\u00f3n de alojamiento para hasta 18 personas? Estamos abiertos a charlar contigo y ayudarte realizar tus actividades aqu\u00ed. Tambi\u00e9n esta la posibilidad de colaborar con profesionales de la zona: Cocineros, t\u00e9cnicos de luz y sonido, docentes para impartir &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/espaciokuatro.eu\/index.php\/2022\/07\/06\/taller-de-inmersion-sonora-vacaciones\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Residencias Art\u00edsticas, Talleres, Retiros, Actuaciones y Convivencias&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-276","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/posts\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":17,"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/posts\/276\/revisions"}],"predecessor-version":[{"id":404,"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/posts\/276\/revisions\/404"}],"wp:attachment":[{"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/media?parent=276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/categories?post=276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espaciokuatro.eu\/index.php\/wp-json\/wp\/v2\/tags?post=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}